{"id":167,"date":"2017-08-07T14:48:45","date_gmt":"2017-08-07T14:48:45","guid":{"rendered":"https:\/\/pacoroncerorestaurante.com\/?page_id=167"},"modified":"2025-11-29T10:15:18","modified_gmt":"2025-11-29T09:15:18","slug":"menus","status":"publish","type":"page","link":"https:\/\/pacoroncerorestaurante.com\/es\/menus\/","title":{"rendered":"Menus"},"content":{"rendered":"<div id='av-layout-grid-1'  class='av-layout-grid-container av-41xk7r-052b80641b05dcc7251306b8007c9d76 entry-content-wrapper main_color av-flex-cells  avia-builder-el-0  el_before_av_section  avia-builder-el-first   container_wrap sidebar_right'  >\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3wdy9b-a57ced4e25b6863b86bc19fdc171deee\">\n.flex_cell.av-3wdy9b-a57ced4e25b6863b86bc19fdc171deee{\nvertical-align:top;\nbackground:url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/fondo-reservas.jpg) 0% 0% no-repeat scroll ;\n}\n.responsive #top #wrap_all .flex_cell.av-3wdy9b-a57ced4e25b6863b86bc19fdc171deee{\npadding:30px 30px 30px 30px !important;\n}\n<\/style>\n<div class='flex_cell av-3wdy9b-a57ced4e25b6863b86bc19fdc171deee av-gridrow-cell av_one_full no_margin  avia-builder-el-1  avia-builder-el-no-sibling '  ><div class='flex_cell_inner'><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gfcpj-e2e003376d54e71d65aff5112de1ce3c\">\n.flex_column.av-gfcpj-e2e003376d54e71d65aff5112de1ce3c{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-gfcpj-e2e003376d54e71d65aff5112de1ce3c av_one_fourth  avia-builder-el-2  el_before_av_one_half  avia-builder-el-first  first flex_column_div av-zero-column-padding  '     ><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-150d1r-d6eac0dcad4adbe135bcc906daaa4a07\">\n.flex_column.av-150d1r-d6eac0dcad4adbe135bcc906daaa4a07{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-150d1r-d6eac0dcad4adbe135bcc906daaa4a07 av_one_half  avia-builder-el-3  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-zero-column-padding  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m9ck59vk-1bf590f308b64c6995cf366f30073056\">\n#top .av-special-heading.av-m9ck59vk-1bf590f308b64c6995cf366f30073056{\npadding-bottom:10px;\ncolor:#232323;\nfont-size:60px;\n}\nbody .av-special-heading.av-m9ck59vk-1bf590f308b64c6995cf366f30073056 .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n#top #wrap_all .av-special-heading.av-m9ck59vk-1bf590f308b64c6995cf366f30073056 .av-special-heading-tag{\nfont-size:60px;\n}\n.av-special-heading.av-m9ck59vk-1bf590f308b64c6995cf366f30073056 .special-heading-inner-border{\nborder-color:#232323;\n}\n.av-special-heading.av-m9ck59vk-1bf590f308b64c6995cf366f30073056 .av-subheading{\nfont-size:15px;\n}\n\n@media only screen and (min-width: 480px) and (max-width: 767px){ \n#top #wrap_all .av-special-heading.av-m9ck59vk-1bf590f308b64c6995cf366f30073056 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n\n@media only screen and (max-width: 479px){ \n#top #wrap_all .av-special-heading.av-m9ck59vk-1bf590f308b64c6995cf366f30073056 .av-special-heading-tag{\nfont-size:0.8em;\n}\n}\n<\/style>\n<div  class='av-special-heading av-m9ck59vk-1bf590f308b64c6995cf366f30073056 av-special-heading-h1 custom-color-heading blockquote modern-quote modern-centered  avia-builder-el-4  el_before_av_hr  avia-builder-el-first  av-inherit-size'><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Nuestros Men\u00fas<\/h1><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n<div  class='hr av-z43uf-82e087aa361f44a44e4910bf0173e3c4 hr-default  avia-builder-el-5  el_after_av_heading  el_before_av_textblock '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-m9ck5ui1-458c0773518b661873e2ac2da2036a6c\">\n#top .av_textblock_section.av-m9ck5ui1-458c0773518b661873e2ac2da2036a6c .avia_textblock{\nfont-size:16px;\ncolor:#000000;\n}\n<\/style>\n<section  class='av_textblock_section av-m9ck5ui1-458c0773518b661873e2ac2da2036a6c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock av_inherit_color'  itemprop=\"text\" ><p>La cocina de Paco Roncero a\u00fana la <strong>tradici\u00f3n gastron\u00f3mica<\/strong> espa\u00f1ola con las <strong>corrientes m\u00e1s innovadoras<\/strong> del panorama culinario internacional, pero sobre todo nace desde Madrid.<\/p>\n<p>Desde el <strong>coraz\u00f3n de la ciudad<\/strong>, con su historia, su energ\u00eda y su mezcla constante de pasado y futuro, el chef ha creado una propuesta profundamente personal.<\/p>\n<p>A trav\u00e9s de tres men\u00fas dise\u00f1ados para despertar emociones, Paco Roncero invita al comensal a un viaje sensorial donde el <strong>producto de excelencia, la creatividad y la t\u00e9cnica<\/strong> se combinan en perfecto equilibrio.<\/p>\n<p>Cada plato es un reflejo de su trayectoria, pero tambi\u00e9n de <strong>Madrid: castiza y cosmopolita, vibrante y dual<\/strong>. Porque Madrid no se queda quieta. Evoluciona, respira, se transforma. Y nosotros con ella.<\/p>\n<p>Una cocina que mira a la tradici\u00f3n para reinterpretarla y acompa\u00f1arla de los nuevos sabores que llegan y tambi\u00e9n son Madrid.<\/p>\n<p>Porque Madrid no se entiende sin sus sabores. Y los sabores de Paco Roncero Restaurante, no se entienden sin Madrid.<\/p>\n<p><strong>Men\u00fa Gran Madrid \u2013 310\u20ac<\/strong><br \/>\nLa experiencia m\u00e1s extensa y representativa. 25 elaboraciones con las que descubrir el pasado, presente y futuro de la cocina de Paco Roncero.<\/p>\n<p><strong>Men\u00fa Madrid, Madrid, Madrid \u2013 240\u20ac<\/strong><br \/>\n23 elaboraciones para un viaje gastron\u00f3mico pensado para quienes buscan una experiencia profunda y delicada.<\/p>\n<p><strong>Men\u00fa Esencia laborables\u2013 190\u20ac <\/strong><strong>(jueves y viernes mediod\u00eda)\/<\/strong><strong>280\u20ac (con maridaje)*<\/strong><br \/>\nUna versi\u00f3n m\u00e1s breve, con 15 elaboraciones, perfecta para disfrutar mediod\u00edas laborables (jueves y viernes).<\/p>\n<p><strong>Men\u00fa Esencia (noches y s\u00e1bados)\u2013 280 \u20ac (con maridaje)*<\/strong><br \/>\n15 elaboraciones acompa\u00f1adas de una armon\u00eda de vinos cuidadosamente seleccionada por nuestro equipo de sumilleres, para descubrir nuestra casa.<\/p>\n<p><strong>Maridajes<\/strong><br \/>\nNuestros sumilleres, liderados por Mar\u00eda Jos\u00e9 Huertas, seleccionan vinos que evolucionan con las estaciones y elevan cada elaboraci\u00f3n con armon\u00edas precisas y sorprendentes.<\/p>\n<p>Los maridajes est\u00e1n disponibles exclusivamente para los men\u00fas Madrid, Madrid, Madrid y Gran Madrid, y pueden elegirse en el restaurante entre tres propuestas:<\/p>\n<ul>\n<li><strong>Vinos Nacionales \u2013 125\u20ac<\/strong><\/li>\n<li><strong>Vinos del viejo &amp; nuevo Mundo \u2013 185\u20ac<\/strong><\/li>\n<li><strong>Grandes Vinos \u2013 295\u20ac<\/strong><\/li>\n<\/ul>\n<\/div><\/section><\/p><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7tx1r-da2d31b1ba19313203213386563d0ff9\">\n.flex_column.av-7tx1r-da2d31b1ba19313203213386563d0ff9{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-7tx1r-da2d31b1ba19313203213386563d0ff9 av_one_fourth  avia-builder-el-7  el_after_av_one_half  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><\/div><\/p>\n<\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-9thfr-ea9d4777263888c61c0d1393f5944e2a\">\n.avia-section.av-9thfr-ea9d4777263888c61c0d1393f5944e2a{\nbackground-repeat:no-repeat;\nbackground-image:url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/180922_Terraza-del-Casino__W2I1480-1.jpg);\nbackground-position:50% 50%;\nbackground-attachment:fixed;\n}\n.avia-section.av-9thfr-ea9d4777263888c61c0d1393f5944e2a .av-section-color-overlay{\nopacity:0.5;\nbackground-color:#80929f;\n}\n<\/style>\n<div id='av_section_1'  class='avia-section av-9thfr-ea9d4777263888c61c0d1393f5944e2a main_color avia-section-default avia-no-shadow  avia-builder-el-8  el_after_av_layout_row  el_before_av_masonry_gallery  avia-full-stretch avia-bg-style-fixed av-section-color-overlay-active container_wrap sidebar_right'  data-section-bg-repeat='stretch'><div class=\"av-section-color-overlay-wrap\"><div class=\"av-section-color-overlay\"><\/div><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-167'><div class='entry-content-wrapper clearfix'>\n<div  class='avia-button-wrap av-90muv-f7a371581dab6708e32fce08666795c0-wrap avia-button-center  avia-builder-el-9  el_before_av_button  avia-builder-el-first '><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Menu-Paco-Roncero-Restaurante.pdf\" class=\"avia-button av-90muv-f7a371581dab6708e32fce08666795c0 av-link-btn avia-icon_select-yes-left-icon avia-size-x-large avia-position-center av-icon-on-hover avia-color-dark\" target=\"_blank\" rel=\"noopener noreferrer\" aria-label=\"EXPLORA MEN\u00daS COMPLETO\"><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue823' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >EXPLORA MEN\u00daS COMPLETO<\/span><\/a><\/div>\n<div  class='avia-button-wrap av-mai85z5q-4307a4d37a905312f56e5989d063d3a2-wrap avia-button-center  avia-builder-el-10  el_after_av_button  avia-builder-el-last '><a href='https:\/\/pacoroncerorestaurante.com\/es\/reserva\/'  class='avia-button av-mai85z5q-4307a4d37a905312f56e5989d063d3a2 av-link-btn avia-icon_select-yes-left-icon avia-size-x-large avia-position-center av-icon-on-hover avia-color-dark'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"RESERVA MESA\"><span class='avia_button_icon avia_button_icon_left' aria-hidden='true' data-av_icon='\ue8ed' data-av_iconfont='entypo-fontello'><\/span><span class='avia_iconbox_title' >RESERVA MESA<\/span><\/a><\/div>\n<\/p>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2gvvcf-7fa1c28b2c827bad4556ad4ffc49c51e\">\n#top .av-masonry.av-2gvvcf-7fa1c28b2c827bad4556ad4ffc49c51e{\nbackground-color:#ffffff;\n}\n<\/style>\n<div id='av-masonry-1' class='av-masonry av-2gvvcf-7fa1c28b2c827bad4556ad4ffc49c51e noHover av-fixed-size av-large-gap av-hover-overlay-active av-masonry-animation-active av-masonry-col-4 av-caption-always av-caption-style- av-masonry-gallery av-small-hide av-mini-hide ' data-post_id=\"167\"><div class=\"av-masonry-container isotope av-js-disabled\"><div class='av-masonry-entry isotope-item av-masonry-item-no-image '><\/div><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Pizza-aerea-de-trufa1-1030x687.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Pizza-aerea-de-trufa1-1030x687.jpg 1030w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Pizza-aerea-de-trufa1-300x200.jpg 300w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Pizza-aerea-de-trufa1-768x512.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Pizza-aerea-de-trufa1-1536x1025.jpg 1536w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Pizza-aerea-de-trufa1-2048x1366.jpg 2048w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Pizza-aerea-de-trufa1-1500x1001.jpg 1500w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Pizza-aerea-de-trufa1-705x470.jpg 705w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image Pizza aerea de trufa1\"  id='av-masonry-1-item-4426' data-av-masonry-item='4426' class='av-masonry-entry isotope-item post-4426 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Pizza aerea de trufa1\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Pizza-aerea-de-trufa1-705x470.jpg);\"  title=\"Pizza aerea de trufa1\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Pizza aerea de trufa1<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Tarta a\u00e9rea de trufa negra<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Olivos-1-1030x797.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Olivos-1-1030x797.jpg 1030w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Olivos-1-300x232.jpg 300w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Olivos-1-768x594.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Olivos-1-1536x1188.jpg 1536w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Olivos-1-2048x1584.jpg 2048w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Olivos-1-1500x1160.jpg 1500w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Olivos-1-705x545.jpg 705w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Olivos-1-450x348.jpg 450w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image Olivos\"  id='av-masonry-1-item-2853' data-av-masonry-item='2853' class='av-masonry-entry isotope-item post-2853 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Olivos\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Olivos-1-705x545.jpg);\"  title=\"Olivos\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Olivos<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Olivo Milenario<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Salmon-marinado-en-miso-1030x687.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Salmon-marinado-en-miso-1030x687.jpg 1030w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Salmon-marinado-en-miso-300x200.jpg 300w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Salmon-marinado-en-miso-768x512.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Salmon-marinado-en-miso-1536x1024.jpg 1536w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Salmon-marinado-en-miso-2048x1366.jpg 2048w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Salmon-marinado-en-miso-1500x1000.jpg 1500w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Salmon-marinado-en-miso-705x470.jpg 705w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Salmon-marinado-en-miso-450x300.jpg 450w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image Salmon marinado en miso\"  id='av-masonry-1-item-3107' data-av-masonry-item='3107' class='av-masonry-entry isotope-item post-3107 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Salmon marinado en miso\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Salmon-marinado-en-miso-705x470.jpg);\"  title=\"Salmon marinado en miso\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Salmon marinado en miso<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Salm\u00f3n marinado en miso<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Brandada-de-bacalao-1030x687.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Brandada-de-bacalao-1030x687.jpg 1030w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Brandada-de-bacalao-300x200.jpg 300w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Brandada-de-bacalao-768x512.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Brandada-de-bacalao-705x470.jpg 705w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Brandada-de-bacalao-450x300.jpg 450w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Brandada-de-bacalao.jpg 1080w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image Brandada de bacalao\"  id='av-masonry-1-item-2848' data-av-masonry-item='2848' class='av-masonry-entry isotope-item post-2848 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Brandada de bacalao\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Brandada-de-bacalao-705x470.jpg);\"  title=\"Brandada de bacalao\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Brandada de bacalao<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >lemon pie bacalao<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4398-686x1030.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4398-686x1030.jpg 686w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4398-200x300.jpg 200w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4398-768x1152.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4398-1024x1536.jpg 1024w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4398-1000x1500.jpg 1000w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4398-470x705.jpg 470w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4398.jpg 1169w\" data-sizes=\"(max-width: 686px) 100vw, 686px\"  aria-label=\"image _DSC4398\"  id='av-masonry-1-item-4634' data-av-masonry-item='4634' class='av-masonry-entry isotope-item post-4634 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"_DSC4398\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4398-470x705.jpg);\"  title=\"_DSC4398\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >_DSC4398<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Gamba al ajillo<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/corte-parmesano1-687x1030.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/corte-parmesano1-687x1030.jpg 687w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/corte-parmesano1-200x300.jpg 200w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/corte-parmesano1-768x1152.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/corte-parmesano1-1024x1536.jpg 1024w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/corte-parmesano1-1366x2048.jpg 1366w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/corte-parmesano1-1000x1500.jpg 1000w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/corte-parmesano1-470x705.jpg 470w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/corte-parmesano1-scaled.jpg 1707w\" data-sizes=\"(max-width: 687px) 100vw, 687px\"  aria-label=\"image corte parmesano1\"  id='av-masonry-1-item-4420' data-av-masonry-item='4420' class='av-masonry-entry isotope-item post-4420 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"corte parmesano1\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/corte-parmesano1-470x705.jpg);\"  title=\"corte parmesano1\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >corte parmesano1<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Corte helado de queso parmesano<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Steak-tartar-con-caviar-ahumado-1030x799.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Steak-tartar-con-caviar-ahumado-1030x799.jpg 1030w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Steak-tartar-con-caviar-ahumado-300x233.jpg 300w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Steak-tartar-con-caviar-ahumado-768x595.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Steak-tartar-con-caviar-ahumado-1536x1191.jpg 1536w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Steak-tartar-con-caviar-ahumado-2048x1588.jpg 2048w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Steak-tartar-con-caviar-ahumado-1500x1163.jpg 1500w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Steak-tartar-con-caviar-ahumado-705x547.jpg 705w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Steak-tartar-con-caviar-ahumado-450x349.jpg 450w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image Steak tartar con caviar ahumado\"  id='av-masonry-1-item-3109' data-av-masonry-item='3109' class='av-masonry-entry isotope-item post-3109 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Steak tartar con caviar ahumado\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Steak-tartar-con-caviar-ahumado-705x547.jpg);\"  title=\"Steak tartar con caviar ahumado\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Steak tartar con caviar ahumado<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Steak tartar con caviar ahumado<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4107-687x1030.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4107-687x1030.jpg 687w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4107-200x300.jpg 200w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4107-768x1152.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4107-1024x1536.jpg 1024w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4107-1366x2048.jpg 1366w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4107-1000x1500.jpg 1000w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4107-470x705.jpg 470w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4107-scaled.jpg 1707w\" data-sizes=\"(max-width: 687px) 100vw, 687px\"  aria-label=\"image _DSC4107\"  id='av-masonry-1-item-4636' data-av-masonry-item='4636' class='av-masonry-entry isotope-item post-4636 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"_DSC4107\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/DSC4107-470x705.jpg);\"  title=\"_DSC4107\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >_DSC4107<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Huerto<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/ventresca-atun-rojo1-1030x687.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/ventresca-atun-rojo1-1030x687.jpg 1030w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/ventresca-atun-rojo1-300x200.jpg 300w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/ventresca-atun-rojo1-768x512.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/ventresca-atun-rojo1-1536x1024.jpg 1536w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/ventresca-atun-rojo1-2048x1366.jpg 2048w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/ventresca-atun-rojo1-1500x1000.jpg 1500w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/ventresca-atun-rojo1-705x470.jpg 705w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image ventresca atun rojo1\"  id='av-masonry-1-item-4428' data-av-masonry-item='4428' class='av-masonry-entry isotope-item post-4428 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"ventresca atun rojo1\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/ventresca-atun-rojo1-705x470.jpg);\"  title=\"ventresca atun rojo1\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >ventresca atun rojo1<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Ventresca de at\u00fan rojo<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Manjar-blanco-687x1030.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Manjar-blanco-687x1030.jpg 687w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Manjar-blanco-200x300.jpg 200w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Manjar-blanco-768x1151.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Manjar-blanco-1025x1536.jpg 1025w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Manjar-blanco-1366x2048.jpg 1366w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Manjar-blanco-1000x1500.jpg 1000w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Manjar-blanco-470x705.jpg 470w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Manjar-blanco-scaled.jpg 1708w\" data-sizes=\"(max-width: 687px) 100vw, 687px\"  aria-label=\"image Manjar blanco\"  id='av-masonry-1-item-4418' data-av-masonry-item='4418' class='av-masonry-entry isotope-item post-4418 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Manjar blanco\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Manjar-blanco-470x705.jpg);\"  title=\"Manjar blanco\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Manjar blanco<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Manjar blanco<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Lenguado-a-la-mantequilla-negra-1030x687.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Lenguado-a-la-mantequilla-negra-1030x687.jpg 1030w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Lenguado-a-la-mantequilla-negra-300x200.jpg 300w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Lenguado-a-la-mantequilla-negra-768x512.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Lenguado-a-la-mantequilla-negra-1536x1024.jpg 1536w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Lenguado-a-la-mantequilla-negra-2048x1366.jpg 2048w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Lenguado-a-la-mantequilla-negra-1500x1000.jpg 1500w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Lenguado-a-la-mantequilla-negra-705x470.jpg 705w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Lenguado-a-la-mantequilla-negra-450x300.jpg 450w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image Lenguado a la mantequilla negra\"  id='av-masonry-1-item-3104' data-av-masonry-item='3104' class='av-masonry-entry isotope-item post-3104 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Lenguado a la mantequilla negra\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Lenguado-a-la-mantequilla-negra-705x470.jpg);\"  title=\"Lenguado a la mantequilla negra\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Lenguado a la mantequilla negra<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Lenguado a la mantequilla negra<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Wellington-de-rabo-de-toro-1-1030x687.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Wellington-de-rabo-de-toro-1-1030x687.jpg 1030w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Wellington-de-rabo-de-toro-1-300x200.jpg 300w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Wellington-de-rabo-de-toro-1-768x512.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Wellington-de-rabo-de-toro-1-1536x1024.jpg 1536w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Wellington-de-rabo-de-toro-1-2048x1366.jpg 2048w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Wellington-de-rabo-de-toro-1-1500x1000.jpg 1500w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Wellington-de-rabo-de-toro-1-705x470.jpg 705w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\"  aria-label=\"image Wellington de rabo de toro 1\"  id='av-masonry-1-item-4430' data-av-masonry-item='4430' class='av-masonry-entry isotope-item post-4430 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Wellington de rabo de toro 1\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Wellington-de-rabo-de-toro-1-705x470.jpg);\"  title=\"Wellington de rabo de toro 1\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Wellington de rabo de toro 1<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Wellintong de rabo de toro<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><a href=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Maiz1-687x1030.jpg\" data-srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Maiz1-687x1030.jpg 687w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Maiz1-200x300.jpg 200w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Maiz1-768x1151.jpg 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Maiz1-1024x1536.jpg 1024w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Maiz1-1366x2048.jpg 1366w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Maiz1-1000x1500.jpg 1000w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Maiz1-470x705.jpg 470w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Maiz1-scaled.jpg 1707w\" data-sizes=\"(max-width: 687px) 100vw, 687px\"  aria-label=\"image Ma\u00edz1\"  id='av-masonry-1-item-4422' data-av-masonry-item='4422' class='av-masonry-entry isotope-item post-4422 attachment type-attachment status-inherit hentry  av-masonry-item-with-image' title=\"Ma\u00edz1\" alt=\"\"    itemprop=\"thumbnailUrl\" ><div class='av-inner-masonry-sizer'><\/div><figure class='av-inner-masonry main_color'><div class=\"av-masonry-outerimage-container\"><div class='av-masonry-image-container' style=\"background-image: url(https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/Maiz1-470x705.jpg);\"  title=\"Ma\u00edz1\" ><\/div><\/div><figcaption class='av-inner-masonry-content site-background'><div class='av-inner-masonry-content-pos'><div class='av-inner-masonry-content-pos-content'><div class='avia-arrow'><\/div><h3 class='av-masonry-entry-title entry-title '  itemprop=\"headline\" >Ma\u00edz1<\/h3><div class='av-masonry-entry-content entry-content'  itemprop=\"text\" >Ma\u00edz<\/div><\/div><\/div><\/figcaption><\/figure><\/a><!--end av-masonry entry--><\/div><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2ba3gf-1ff71b30c462b95eb185d4849860ad46\">\n.avia-section.av-2ba3gf-1ff71b30c462b95eb185d4849860ad46{\nbackground-color:#7d854c;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_2'  class='avia-section av-2ba3gf-1ff71b30c462b95eb185d4849860ad46 main_color avia-section-small avia-no-border-styling  avia-builder-el-12  el_after_av_masonry_gallery  el_before_av_section  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-167'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-202s5z-066704b7ff53b936b6cf231d63e617f4\">\n#top .hr.hr-invisible.av-202s5z-066704b7ff53b936b6cf231d63e617f4{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-202s5z-066704b7ff53b936b6cf231d63e617f4 hr-invisible  avia-builder-el-13  el_before_av_image  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1vpjo7-32e37766a85d88b9209431a246fb3e74\">\n.avia-image-container.av-1vpjo7-32e37766a85d88b9209431a246fb3e74 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-1vpjo7-32e37766a85d88b9209431a246fb3e74 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-1vpjo7-32e37766a85d88b9209431a246fb3e74 av-styling- avia-align-center  avia-builder-el-14  el_after_av_hr  avia-builder-el-last '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2485 avia-img-lazy-loading-not-2485 avia_image ' src=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/PACO-RONCERO-NEGATIVO-1-300x65.png\" alt='' title='PACO RONCERO NEGATIVO'  height=\"65\" width=\"300\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/PACO-RONCERO-NEGATIVO-1-300x65.png 300w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/PACO-RONCERO-NEGATIVO-1-768x166.png 768w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/PACO-RONCERO-NEGATIVO-1-1030x223.png 1030w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/PACO-RONCERO-NEGATIVO-1-1500x325.png 1500w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/PACO-RONCERO-NEGATIVO-1-705x153.png 705w, https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/PACO-RONCERO-NEGATIVO-1-450x97.png 450w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/div><\/div><\/div>\n\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-67urr-f23ca45fed3571b61262ba63c816e752\">\n.avia-section.av-67urr-f23ca45fed3571b61262ba63c816e752{\nbackground-color:#ffffff;\nbackground-image:unset;\n}\n<\/style>\n<div id='av_section_3'  class='avia-section av-67urr-f23ca45fed3571b61262ba63c816e752 main_color avia-section-small avia-no-border-styling  avia-builder-el-15  el_after_av_section  avia-builder-el-last  avia-bg-style-scroll container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-167'><div class='entry-content-wrapper clearfix'>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1kxuvr-29c739da52e6b72341274cfd91181dcb\">\n#top .hr.hr-invisible.av-1kxuvr-29c739da52e6b72341274cfd91181dcb{\nheight:20px;\n}\n<\/style>\n<div  class='hr av-1kxuvr-29c739da52e6b72341274cfd91181dcb hr-invisible  avia-builder-el-16  el_before_av_one_fourth  avia-builder-el-first '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1cdyrz-9d0b249fa06615961426f38e87bc0373\">\n.flex_column.av-1cdyrz-9d0b249fa06615961426f38e87bc0373{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-1cdyrz-9d0b249fa06615961426f38e87bc0373 av_one_fourth  avia-builder-el-17  el_after_av_hr  el_before_av_one_fourth  first flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-16tjhz-5361f7904f5d0c39e8bfcc061c155a84\">\n.avia-image-container.av-16tjhz-5361f7904f5d0c39e8bfcc061c155a84 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-16tjhz-5361f7904f5d0c39e8bfcc061c155a84 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-16tjhz-5361f7904f5d0c39e8bfcc061c155a84 av-styling- avia-align-center  avia-builder-el-18  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2700 avia-img-lazy-loading-not-2700 avia_image ' src=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/logo_leguidemichelin_negro-e1599204444533.png\" alt='' title='logo_leguidemichelin_negro'  height=\"88\" width=\"200\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-3wb1z-9b8a07953546c1365a24d34eaa665a9e\">\n.flex_column.av-3wb1z-9b8a07953546c1365a24d34eaa665a9e{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-3wb1z-9b8a07953546c1365a24d34eaa665a9e av_one_fourth  avia-builder-el-19  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-x5tr3-818f0d44568f959ae06a84b03462a3b3\">\n.avia-image-container.av-x5tr3-818f0d44568f959ae06a84b03462a3b3 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-x5tr3-818f0d44568f959ae06a84b03462a3b3 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-x5tr3-818f0d44568f959ae06a84b03462a3b3 av-styling- avia-align-center  avia-builder-el-20  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-3209 avia-img-lazy-loading-not-3209 avia_image ' src=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/paco-roncero-soles-80.png\" alt='' title='paco-roncero-soles-80'  height=\"118\" width=\"80\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-suti7-cb130535391b4dc0f2f601a599a2ff21\">\n.flex_column.av-suti7-cb130535391b4dc0f2f601a599a2ff21{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-suti7-cb130535391b4dc0f2f601a599a2ff21 av_one_fourth  avia-builder-el-21  el_after_av_one_fourth  el_before_av_one_fourth  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-k8t0f-215568e420af36b938b06029bd63831f\">\n.avia-image-container.av-k8t0f-215568e420af36b938b06029bd63831f img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-k8t0f-215568e420af36b938b06029bd63831f .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-k8t0f-215568e420af36b938b06029bd63831f av-styling- avia-align-center  avia-builder-el-22  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-3212 avia-img-lazy-loading-not-3212 avia_image ' src=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/paco-roncero-best-chef-70.png\" alt='' title='paco-roncero-best-chef-70'  height=\"130\" width=\"70\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-felen-efd17971f2c8dff227215788e0408562\">\n.flex_column.av-felen-efd17971f2c8dff227215788e0408562{\nborder-radius:0px 0px 0px 0px;\npadding:0px 0px 0px 0px;\n}\n<\/style>\n<div  class='flex_column av-felen-efd17971f2c8dff227215788e0408562 av_one_fourth  avia-builder-el-23  el_after_av_one_fourth  avia-builder-el-last  flex_column_div av-zero-column-padding  '     ><style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-6poqv-6c41237b4fd797d1ead2b8012f0191f1\">\n.avia-image-container.av-6poqv-6c41237b4fd797d1ead2b8012f0191f1 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-6poqv-6c41237b4fd797d1ead2b8012f0191f1 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-6poqv-6c41237b4fd797d1ead2b8012f0191f1 av-styling- avia-align-center  avia-builder-el-24  avia-builder-el-no-sibling '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2596 avia-img-lazy-loading-not-2596 avia_image ' src=\"https:\/\/pacoroncerorestaurante.com\/wp-content\/uploads\/50BEST-DISCOVERY-MARK-BLACK-e1575277443499.png\" alt='' title='50BEST-DISCOVERY-MARK-BLACK'  height=\"61\" width=\"200\"  itemprop=\"thumbnailUrl\"  \/><\/div><\/div><\/div><\/div>\n<\/div><\/div><\/div><!-- close content main div --><\/div><\/div><div id='after_section_3'  class='main_color av_default_container_wrap container_wrap sidebar_right'  ><div class='container av-section-cont-open' ><div class='template-page content  av-content-small alpha units'><div class='post-entry post-entry-type-page post-entry-167'><div class='entry-content-wrapper clearfix'>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-167","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/pacoroncerorestaurante.com\/es\/wp-json\/wp\/v2\/pages\/167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pacoroncerorestaurante.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pacoroncerorestaurante.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pacoroncerorestaurante.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/pacoroncerorestaurante.com\/es\/wp-json\/wp\/v2\/comments?post=167"}],"version-history":[{"count":201,"href":"https:\/\/pacoroncerorestaurante.com\/es\/wp-json\/wp\/v2\/pages\/167\/revisions"}],"predecessor-version":[{"id":5307,"href":"https:\/\/pacoroncerorestaurante.com\/es\/wp-json\/wp\/v2\/pages\/167\/revisions\/5307"}],"wp:attachment":[{"href":"https:\/\/pacoroncerorestaurante.com\/es\/wp-json\/wp\/v2\/media?parent=167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}